{"id":4512,"date":"2024-12-22T18:16:20","date_gmt":"2024-12-22T17:16:20","guid":{"rendered":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188.jpg"},"modified":"2024-12-22T18:16:20","modified_gmt":"2024-12-22T17:16:20","slug":"img_0188-2","status":"inherit","type":"attachment","link":"https:\/\/explore360.nu\/sv\/destinations\/sri-lanka-pearl-in-the-indian-ocean\/img_0188-2\/","title":{"rendered":"IMG_0188"},"author":3,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-4512","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG_0188 - Explore360\u00b0- Motorcycle Adventures<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG_0188 - Explore360\u00b0- Motorcycle Adventures\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Explore360\u00b0- Motorcycle Adventures\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/explore360\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/IMG_0188-scaled-e1734888060597.jpg\",\"url\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/IMG_0188-scaled-e1734888060597.jpg\",\"name\":\"IMG_0188 - Explore360\u00b0- Motorcycle Adventures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/explore360.nu\\\/#website\"},\"datePublished\":\"2024-12-22T17:16:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/IMG_0188-scaled-e1734888060597.jpg#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/IMG_0188-scaled-e1734888060597.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/IMG_0188-scaled-e1734888060597.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/explore360.nu\\\/sv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SRI LANKA&#8217;s secrets\",\"item\":\"https:\\\/\\\/explore360.nu\\\/sv\\\/destinations\\\/sri-lanka-pearl-in-the-indian-ocean\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IMG_0188\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/explore360.nu\\\/#website\",\"url\":\"https:\\\/\\\/explore360.nu\\\/\",\"name\":\"Explore360\u00b0- Motorcycle Adventures\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/explore360.nu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/explore360.nu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/explore360.nu\\\/#organization\",\"name\":\"explore360\",\"url\":\"https:\\\/\\\/explore360.nu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/explore360.nu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/explore360.jpg\",\"contentUrl\":\"https:\\\/\\\/explore360.nu\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/explore360.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"explore360\"},\"image\":{\"@id\":\"https:\\\/\\\/explore360.nu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/explore360\\\/\",\"https:\\\/\\\/www.instagram.com\\\/explore36o\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/chris-wilthuis-800802a\\\/?trk=nav_responsive_tab_profile\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCjTAmMoiZ-FTskT6lQnFDag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG_0188 - Explore360\u00b0- Motorcycle Adventures","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","og_locale":"sv_SE","og_type":"article","og_title":"IMG_0188 - Explore360\u00b0- Motorcycle Adventures","og_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","og_site_name":"Explore360\u00b0- Motorcycle Adventures","article_publisher":"https:\/\/www.facebook.com\/explore360\/","og_image":[{"width":1440,"height":2560,"url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","name":"IMG_0188 - Explore360\u00b0- Motorcycle Adventures","isPartOf":{"@id":"https:\/\/explore360.nu\/#website"},"datePublished":"2024-12-22T17:16:20+00:00","breadcrumb":{"@id":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/explore360.nu\/sv\/"},{"@type":"ListItem","position":2,"name":"SRI LANKA&#8217;s secrets","item":"https:\/\/explore360.nu\/sv\/destinations\/sri-lanka-pearl-in-the-indian-ocean\/"},{"@type":"ListItem","position":3,"name":"IMG_0188"}]},{"@type":"WebSite","@id":"https:\/\/explore360.nu\/#website","url":"https:\/\/explore360.nu\/","name":"Explore360\u00b0- Motorcycle Adventures","description":"","publisher":{"@id":"https:\/\/explore360.nu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore360.nu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/explore360.nu\/#organization","name":"explore360","url":"https:\/\/explore360.nu\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/explore360.nu\/#\/schema\/logo\/image\/","url":"https:\/\/explore360.nu\/wp-content\/uploads\/2020\/05\/explore360.jpg","contentUrl":"https:\/\/explore360.nu\/wp-content\/uploads\/2020\/05\/explore360.jpg","width":1920,"height":1080,"caption":"explore360"},"image":{"@id":"https:\/\/explore360.nu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/explore360\/","https:\/\/www.instagram.com\/explore36o\/","https:\/\/www.linkedin.com\/in\/chris-wilthuis-800802a\/?trk=nav_responsive_tab_profile","https:\/\/www.youtube.com\/channel\/UCjTAmMoiZ-FTskT6lQnFDag"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-169x300.jpg 169w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-576x1024.jpg 576w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-768x1365.jpg 768w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-864x1536.jpg 864w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-1152x2048.jpg 1152w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-450x800.jpg 450w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-720x1280.jpg 720w, https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled.jpg 1440w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1440,"height":2560,"file":"2022\/01\/IMG_0188-scaled.jpg","filesize":509627,"sizes":{"medium":{"file":"IMG_0188-169x300.jpg","width":169,"height":300,"filesize":20502,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-169x300.jpg"},"large":{"file":"IMG_0188-576x1024.jpg","width":576,"height":1024,"filesize":127221,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-576x1024.jpg"},"thumbnail":{"file":"IMG_0188-150x150.jpg","width":150,"height":150,"filesize":11886,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-150x150.jpg"},"medium_large":{"file":"IMG_0188-768x1365.jpg","width":768,"height":1365,"filesize":196637,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-768x1365.jpg"},"1536x1536":{"file":"IMG_0188-864x1536.jpg","width":864,"height":1536,"filesize":234025,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-864x1536.jpg"},"2048x2048":{"file":"IMG_0188-1152x2048.jpg","width":1152,"height":2048,"filesize":362524,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-1152x2048.jpg"},"imgmed":{"file":"IMG_0188-450x800.jpg","width":450,"height":800,"filesize":87670,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-450x800.jpg"},"imglarge":{"file":"IMG_0188-720x1280.jpg","width":720,"height":1280,"filesize":177825,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-720x1280.jpg"},"gform-image-choice-sm":{"file":"IMG_0188-300x300.jpg","width":300,"height":300,"filesize":29914,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-300x300.jpg"},"gform-image-choice-md":{"file":"IMG_0188-400x400.jpg","width":400,"height":400,"filesize":45962,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-400x400.jpg"},"gform-image-choice-lg":{"file":"IMG_0188-600x600.jpg","width":600,"height":600,"filesize":87518,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-600x600.jpg"},"full":{"file":"IMG_0188-scaled-e1734888060597.jpg","width":1440,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"iPhone 15 Pro Max","caption":"","created_timestamp":"1733230185","copyright":"","focal_length":"15.659999847383","iso":"50","shutter_speed":"0.0091743119266055","title":"","orientation":"1","keywords":[]},"original_image":"IMG_0188.jpg"},"post":4325,"source_url":"https:\/\/explore360.nu\/wp-content\/uploads\/2022\/01\/IMG_0188-scaled-e1734888060597.jpg","_links":{"self":[{"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/media\/4512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/comments?post=4512"}],"wp:attached-to":[{"embeddable":true,"post_type":"destinations","id":4325,"href":"https:\/\/explore360.nu\/sv\/wp-json\/wp\/v2\/destinations\/4325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}